{"id":23419527,"date":"2026-02-03T12:23:36","date_gmt":"2026-02-03T10:23:36","guid":{"rendered":"https:\/\/schlagfix.com\/?p=23419527"},"modified":"2026-07-13T10:14:53","modified_gmt":"2026-07-13T08:14:53","slug":"schlagfix-auf-der-intergastra-2026-in-stuttgart","status":"publish","type":"post","link":"https:\/\/schlagfix.com\/en\/2026\/02\/03\/schlagfix-auf-der-intergastra-2026-in-stuttgart\/","title":{"rendered":"Schlagfix auf der Intergastra 2026 in Stuttgart!"},"content":{"rendered":"\n[et_pb_section fb_built=&#8221;1&#8243; _builder_version=&#8221;4.24.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_row _builder_version=&#8221;4.24.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221; min_height=&#8221;302.7px&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.24.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_video _builder_version=&#8221;4.24.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_video][et_pb_text _builder_version=&#8221;4.24.0&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;Montserrat Regular||||||||&#8221; text_font_size=&#8221;15px&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;]<p><span style=\"font-size: 15px;\">Unser Schlagfix-Team wird vom 07.02.2026 bis 11.02.2026 auf der Intergastra in Stuttgart vertreten sein.<\/span><\/p>\n<p><span>Die <\/span><strong><span class=\"theme__color\">INTERGASTRA<\/span><\/strong><span>\u00a0ist die Leitmesse f\u00fcr Hotellerie und Gastronomie. Die Veranstaltung pr\u00e4sentiert sich auf 120.000 m\u00b2 Fl\u00e4che in allen 10 Hallen der Messe Stuttgart und ist mit 1.257 Ausstellerinnen und Aussteller der\u00a0gr\u00f6\u00dfte\u00a0Branchentreffpunkt in Deutschland. Alle zwei Jahre informieren sich 89.497 Fachbesucherinnen und Fachbesucher zu den Schwerpunkten Food\/K\u00fcche, Einrichtung &amp; Tischkultur, Dienstleistung &amp; IT, Getr\u00e4nke, Kaffee sowie Speiseeis. Der Pflichttermin f\u00fcr Gastgeberinnen und Gastgeber bietet Neuheiten, viele M\u00f6glichkeiten zum fachlichen Austausch und erm\u00f6glicht den Blick \u00fcber den Tellerrand.<\/span><\/p>\n<p><span>Entdecke die Fokusthemen der INTERGASTRA 2026 \u2013 sie zeigen, was die Zukunft der Gastronomie und Hotellerie bewegt. Hier treffen neueste Trends, Technologien und Ideen auf bew\u00e4hrte Konzepte, die Effizienz und G\u00e4steerlebnis gleicherma\u00dfen steigern. Die Fokusthemen reichen von Hotel, Food, Getr\u00e4nken und K\u00fcchentechnik \u00fcber Coffee, Vending und Digitales bis hin zu Tabletop, Interior und der integrierten GELATISSIMO.<\/span><\/p>\n<p>&nbsp;<\/p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=&#8221;4.24.0&#8243; _module_preset=&#8221;default&#8221; theme_builder_area=&#8221;post_content&#8221;][et_pb_column _builder_version=&#8221;4.24.0&#8243; _module_preset=&#8221;default&#8221; type=&#8221;4_4&#8243; theme_builder_area=&#8221;post_content&#8221;][et_pb_image src=&#8221;https:\/\/schlagfix.com\/media\/2026\/02\/IG26_WMS_728x90px_DE.gif&#8221; _builder_version=&#8221;4.24.0&#8243; _module_preset=&#8221;default&#8221; theme_builder_area=&#8221;post_content&#8221; title_text=&#8221;IG26_WMS_728x90px_DE&#8221; hover_enabled=&#8221;0&#8243; sticky_enabled=&#8221;0&#8243;][\/et_pb_image][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; theme_builder_area=&#8221;post_content&#8221; _builder_version=&#8221;4.24.0&#8243; _module_preset=&#8221;default&#8221;][\/et_pb_section]\n","protected":false},"excerpt":{"rendered":"<p>Unser Schlagfix-Team wird vom 07.02.2026 bis 11.02.2026 auf der Intergastra in Stuttgart vertreten sein. Die INTERGASTRA\u00a0ist die Leitmesse f\u00fcr Hotellerie und Gastronomie. Die Veranstaltung pr\u00e4sentiert sich auf 120.000 m\u00b2 Fl\u00e4che in allen 10 Hallen der Messe Stuttgart und ist mit 1.257 Ausstellerinnen und Aussteller der\u00a0gr\u00f6\u00dfte\u00a0Branchentreffpunkt in Deutschland. Alle zwei Jahre informieren sich 89.497 Fachbesucherinnen und [&hellip;]<\/p>\n","protected":false},"author":12,"featured_media":23419572,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"2880","footnotes":""},"categories":[1],"tags":[],"dipi_cpt_category":[],"class_list":["post-23419527","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Schlagfix auf der Intergastra 2026 in Stuttgart! - Schlagfix<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/schlagfix.com\/en\/2026\/02\/03\/schlagfix-auf-der-intergastra-2026-in-stuttgart\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Schlagfix auf der Intergastra 2026 in Stuttgart! - Schlagfix\" \/>\n<meta property=\"og:description\" content=\"Unser Schlagfix-Team wird vom 07.02.2026 bis 11.02.2026 auf der Intergastra in Stuttgart vertreten sein. Die INTERGASTRA\u00a0ist die Leitmesse f\u00fcr Hotellerie und Gastronomie. Die Veranstaltung pr\u00e4sentiert sich auf 120.000 m\u00b2 Fl\u00e4che in allen 10 Hallen der Messe Stuttgart und ist mit 1.257 Ausstellerinnen und Aussteller der\u00a0gr\u00f6\u00dfte\u00a0Branchentreffpunkt in Deutschland. Alle zwei Jahre informieren sich 89.497 Fachbesucherinnen und [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/schlagfix.com\/en\/2026\/02\/03\/schlagfix-auf-der-intergastra-2026-in-stuttgart\/\" \/>\n<meta property=\"og:site_name\" content=\"Schlagfix\" \/>\n<meta property=\"article:published_time\" content=\"2026-02-03T10:23:36+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-13T08:14:53+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/schlagfix.com\/media\/2026\/02\/Design-ohne-Titel-2026-02-18T093254.574.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1218\" \/>\n\t<meta property=\"og:image:height\" content=\"703\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"LEHA\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"LEHA\" \/>\n\t<meta name=\"twitter:label2\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/schlagfix.com\\\/2026\\\/02\\\/03\\\/schlagfix-auf-der-intergastra-2026-in-stuttgart\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/schlagfix.com\\\/2026\\\/02\\\/03\\\/schlagfix-auf-der-intergastra-2026-in-stuttgart\\\/\"},\"author\":{\"name\":\"LEHA\",\"@id\":\"https:\\\/\\\/schlagfix.com\\\/#\\\/schema\\\/person\\\/ab3289cf1d3c1cb424e3a8e6afba870d\"},\"headline\":\"Schlagfix auf der Intergastra 2026 in Stuttgart!\",\"datePublished\":\"2026-02-03T10:23:36+00:00\",\"dateModified\":\"2026-07-13T08:14:53+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/schlagfix.com\\\/2026\\\/02\\\/03\\\/schlagfix-auf-der-intergastra-2026-in-stuttgart\\\/\"},\"wordCount\":339,\"image\":{\"@id\":\"https:\\\/\\\/schlagfix.com\\\/2026\\\/02\\\/03\\\/schlagfix-auf-der-intergastra-2026-in-stuttgart\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/schlagfix.com\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/Design-ohne-Titel-2026-02-18T093254.574.png\",\"articleSection\":[\"Uncategorized\"],\"inLanguage\":\"en-GB\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/schlagfix.com\\\/2026\\\/02\\\/03\\\/schlagfix-auf-der-intergastra-2026-in-stuttgart\\\/\",\"url\":\"https:\\\/\\\/schlagfix.com\\\/2026\\\/02\\\/03\\\/schlagfix-auf-der-intergastra-2026-in-stuttgart\\\/\",\"name\":\"Schlagfix auf der Intergastra 2026 in Stuttgart! - Schlagfix\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/schlagfix.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/schlagfix.com\\\/2026\\\/02\\\/03\\\/schlagfix-auf-der-intergastra-2026-in-stuttgart\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/schlagfix.com\\\/2026\\\/02\\\/03\\\/schlagfix-auf-der-intergastra-2026-in-stuttgart\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/schlagfix.com\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/Design-ohne-Titel-2026-02-18T093254.574.png\",\"datePublished\":\"2026-02-03T10:23:36+00:00\",\"dateModified\":\"2026-07-13T08:14:53+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/schlagfix.com\\\/#\\\/schema\\\/person\\\/ab3289cf1d3c1cb424e3a8e6afba870d\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/schlagfix.com\\\/2026\\\/02\\\/03\\\/schlagfix-auf-der-intergastra-2026-in-stuttgart\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/schlagfix.com\\\/2026\\\/02\\\/03\\\/schlagfix-auf-der-intergastra-2026-in-stuttgart\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/schlagfix.com\\\/2026\\\/02\\\/03\\\/schlagfix-auf-der-intergastra-2026-in-stuttgart\\\/#primaryimage\",\"url\":\"https:\\\/\\\/schlagfix.com\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/Design-ohne-Titel-2026-02-18T093254.574.png\",\"contentUrl\":\"https:\\\/\\\/schlagfix.com\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/Design-ohne-Titel-2026-02-18T093254.574.png\",\"width\":1218,\"height\":703},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/schlagfix.com\\\/2026\\\/02\\\/03\\\/schlagfix-auf-der-intergastra-2026-in-stuttgart\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/schlagfix.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Schlagfix auf der Intergastra 2026 in Stuttgart!\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/schlagfix.com\\\/#website\",\"url\":\"https:\\\/\\\/schlagfix.com\\\/\",\"name\":\"Schlagfix\",\"description\":\"vegane Produktwelt von LeHa\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/schlagfix.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/schlagfix.com\\\/#\\\/schema\\\/person\\\/ab3289cf1d3c1cb424e3a8e6afba870d\",\"name\":\"LEHA\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/758438f4756fd112de909023970d5fb702251f52884b3cc7df3a289162989b2b?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/758438f4756fd112de909023970d5fb702251f52884b3cc7df3a289162989b2b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/758438f4756fd112de909023970d5fb702251f52884b3cc7df3a289162989b2b?s=96&d=mm&r=g\",\"caption\":\"LEHA\"},\"url\":\"https:\\\/\\\/schlagfix.com\\\/en\\\/author\\\/leha\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Schlagfix auf der Intergastra 2026 in Stuttgart! - Schlagfix","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/schlagfix.com\/en\/2026\/02\/03\/schlagfix-auf-der-intergastra-2026-in-stuttgart\/","og_locale":"en_GB","og_type":"article","og_title":"Schlagfix auf der Intergastra 2026 in Stuttgart! - Schlagfix","og_description":"Unser Schlagfix-Team wird vom 07.02.2026 bis 11.02.2026 auf der Intergastra in Stuttgart vertreten sein. Die INTERGASTRA\u00a0ist die Leitmesse f\u00fcr Hotellerie und Gastronomie. Die Veranstaltung pr\u00e4sentiert sich auf 120.000 m\u00b2 Fl\u00e4che in allen 10 Hallen der Messe Stuttgart und ist mit 1.257 Ausstellerinnen und Aussteller der\u00a0gr\u00f6\u00dfte\u00a0Branchentreffpunkt in Deutschland. Alle zwei Jahre informieren sich 89.497 Fachbesucherinnen und [&hellip;]","og_url":"https:\/\/schlagfix.com\/en\/2026\/02\/03\/schlagfix-auf-der-intergastra-2026-in-stuttgart\/","og_site_name":"Schlagfix","article_published_time":"2026-02-03T10:23:36+00:00","article_modified_time":"2026-07-13T08:14:53+00:00","og_image":[{"width":1218,"height":703,"url":"https:\/\/schlagfix.com\/media\/2026\/02\/Design-ohne-Titel-2026-02-18T093254.574.png","type":"image\/png"}],"author":"LEHA","twitter_card":"summary_large_image","twitter_misc":{"Written by":"LEHA","Estimated reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/schlagfix.com\/2026\/02\/03\/schlagfix-auf-der-intergastra-2026-in-stuttgart\/#article","isPartOf":{"@id":"https:\/\/schlagfix.com\/2026\/02\/03\/schlagfix-auf-der-intergastra-2026-in-stuttgart\/"},"author":{"name":"LEHA","@id":"https:\/\/schlagfix.com\/#\/schema\/person\/ab3289cf1d3c1cb424e3a8e6afba870d"},"headline":"Schlagfix auf der Intergastra 2026 in Stuttgart!","datePublished":"2026-02-03T10:23:36+00:00","dateModified":"2026-07-13T08:14:53+00:00","mainEntityOfPage":{"@id":"https:\/\/schlagfix.com\/2026\/02\/03\/schlagfix-auf-der-intergastra-2026-in-stuttgart\/"},"wordCount":339,"image":{"@id":"https:\/\/schlagfix.com\/2026\/02\/03\/schlagfix-auf-der-intergastra-2026-in-stuttgart\/#primaryimage"},"thumbnailUrl":"https:\/\/schlagfix.com\/media\/2026\/02\/Design-ohne-Titel-2026-02-18T093254.574.png","articleSection":["Uncategorized"],"inLanguage":"en-GB"},{"@type":"WebPage","@id":"https:\/\/schlagfix.com\/2026\/02\/03\/schlagfix-auf-der-intergastra-2026-in-stuttgart\/","url":"https:\/\/schlagfix.com\/2026\/02\/03\/schlagfix-auf-der-intergastra-2026-in-stuttgart\/","name":"Schlagfix auf der Intergastra 2026 in Stuttgart! - Schlagfix","isPartOf":{"@id":"https:\/\/schlagfix.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/schlagfix.com\/2026\/02\/03\/schlagfix-auf-der-intergastra-2026-in-stuttgart\/#primaryimage"},"image":{"@id":"https:\/\/schlagfix.com\/2026\/02\/03\/schlagfix-auf-der-intergastra-2026-in-stuttgart\/#primaryimage"},"thumbnailUrl":"https:\/\/schlagfix.com\/media\/2026\/02\/Design-ohne-Titel-2026-02-18T093254.574.png","datePublished":"2026-02-03T10:23:36+00:00","dateModified":"2026-07-13T08:14:53+00:00","author":{"@id":"https:\/\/schlagfix.com\/#\/schema\/person\/ab3289cf1d3c1cb424e3a8e6afba870d"},"breadcrumb":{"@id":"https:\/\/schlagfix.com\/2026\/02\/03\/schlagfix-auf-der-intergastra-2026-in-stuttgart\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/schlagfix.com\/2026\/02\/03\/schlagfix-auf-der-intergastra-2026-in-stuttgart\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/schlagfix.com\/2026\/02\/03\/schlagfix-auf-der-intergastra-2026-in-stuttgart\/#primaryimage","url":"https:\/\/schlagfix.com\/media\/2026\/02\/Design-ohne-Titel-2026-02-18T093254.574.png","contentUrl":"https:\/\/schlagfix.com\/media\/2026\/02\/Design-ohne-Titel-2026-02-18T093254.574.png","width":1218,"height":703},{"@type":"BreadcrumbList","@id":"https:\/\/schlagfix.com\/2026\/02\/03\/schlagfix-auf-der-intergastra-2026-in-stuttgart\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/schlagfix.com\/"},{"@type":"ListItem","position":2,"name":"Schlagfix auf der Intergastra 2026 in Stuttgart!"}]},{"@type":"WebSite","@id":"https:\/\/schlagfix.com\/#website","url":"https:\/\/schlagfix.com\/","name":"SCHLAGFIX","description":"vegane Produktwelt von LeHa","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/schlagfix.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Person","@id":"https:\/\/schlagfix.com\/#\/schema\/person\/ab3289cf1d3c1cb424e3a8e6afba870d","name":"LEHA","image":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/secure.gravatar.com\/avatar\/758438f4756fd112de909023970d5fb702251f52884b3cc7df3a289162989b2b?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/758438f4756fd112de909023970d5fb702251f52884b3cc7df3a289162989b2b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/758438f4756fd112de909023970d5fb702251f52884b3cc7df3a289162989b2b?s=96&d=mm&r=g","caption":"LEHA"},"url":"https:\/\/schlagfix.com\/en\/author\/leha\/"}]}},"_links":{"self":[{"href":"https:\/\/schlagfix.com\/en\/wp-json\/wp\/v2\/posts\/23419527","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/schlagfix.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/schlagfix.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/schlagfix.com\/en\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/schlagfix.com\/en\/wp-json\/wp\/v2\/comments?post=23419527"}],"version-history":[{"count":7,"href":"https:\/\/schlagfix.com\/en\/wp-json\/wp\/v2\/posts\/23419527\/revisions"}],"predecessor-version":[{"id":23419900,"href":"https:\/\/schlagfix.com\/en\/wp-json\/wp\/v2\/posts\/23419527\/revisions\/23419900"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/schlagfix.com\/en\/wp-json\/wp\/v2\/media\/23419572"}],"wp:attachment":[{"href":"https:\/\/schlagfix.com\/en\/wp-json\/wp\/v2\/media?parent=23419527"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/schlagfix.com\/en\/wp-json\/wp\/v2\/categories?post=23419527"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/schlagfix.com\/en\/wp-json\/wp\/v2\/tags?post=23419527"},{"taxonomy":"dipi_cpt_category","embeddable":true,"href":"https:\/\/schlagfix.com\/en\/wp-json\/wp\/v2\/dipi_cpt_category?post=23419527"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}